{"id":3467,"date":"2022-11-09T07:09:22","date_gmt":"2022-11-09T07:09:22","guid":{"rendered":"https:\/\/opticomtech.com\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/"},"modified":"2022-11-13T21:58:26","modified_gmt":"2022-11-13T21:58:26","slug":"como-mejorar-las-operaciones-mineras-con-la-videovigilancia","status":"publish","type":"post","link":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/","title":{"rendered":"C\u00f3mo mejorar las operaciones mineras con la videovigilancia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3467\" class=\"elementor elementor-3467 elementor-3459\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-214e9c55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"214e9c55\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5374a2b2\" data-id=\"5374a2b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22e265e4 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"22e265e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Miner\u00eda en la cantera\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ2MSwidXJsIjoiaHR0cHM6XC9cL29wdGljb210ZWNoLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTFcL21pbmluZy12aWRlby1tb25pdG9yaW5nLmpwZyJ9\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring-1024x682.jpg\" class=\"attachment-large size-large wp-image-3461\" alt=\"monitoreo de video minero\" srcset=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring-1024x682.jpg 1024w, https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring-300x200.jpg 300w, https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring-768x512.jpg 768w, https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring-1536x1024.jpg 1536w, https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring-600x400.jpg 600w, https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring.jpg 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Cintas transportadoras y equipos de miner\u00eda en una cantera<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fe5b431 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3fe5b431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ1cmwiOiJodHRwczpcL1wvb3B0aWNvbXRlY2guY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIxXC8wMlwvTUlQLTMyMjAuanBnIiwidHlwZSI6ImltYWdlIiwidGl0bGUiOiJNSVAtMzIyMCJ9\" tabindex=\"-1\"><img decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/CC04-IP2MV_transparent.png\" class=\"attachment-full size-full wp-image-2273\" alt=\"\" srcset=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/CC04-IP2MV_transparent.png 700w, https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/CC04-IP2MV_transparent-300x300.png 300w, https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/CC04-IP2MV_transparent-150x150.png 150w, https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/CC04-IP2MV_transparent-600x600.png 600w, https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/CC04-IP2MV_transparent-100x100.png 100w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Supervise las operaciones mineras con las c\u00e1maras industriales y fiables de Opticom.  <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-253cd01d elementor-widget elementor-widget-button\" data-id=\"253cd01d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/opticomtech.comproduct-category\/industrial\/industrial-cameras\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-pdf\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M181.9 256.1c-5-16-4.9-46.9-2-46.9 8.4 0 7.6 36.9 2 46.9zm-1.7 47.2c-7.7 20.2-17.3 43.3-28.4 62.7 18.3-7 39-17.2 62.9-21.9-12.7-9.6-24.9-23.4-34.5-40.8zM86.1 428.1c0 .8 13.2-5.4 34.9-40.2-6.7 6.3-29.1 24.5-34.9 40.2zM248 160h136v328c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V24C0 10.7 10.7 0 24 0h200v136c0 13.2 10.8 24 24 24zm-8 171.8c-20-12.2-33.3-29-42.7-53.8 4.5-18.5 11.6-46.6 6.2-64.2-4.7-29.4-42.4-26.5-47.8-6.8-5 18.3-.4 44.1 8.1 77-11.6 27.6-28.7 64.6-40.8 85.8-.1 0-.1.1-.2.1-27.1 13.9-73.6 44.5-54.5 68 5.6 6.9 16 10 21.5 10 17.9 0 35.7-18 61.1-61.8 25.8-8.5 54.1-19.1 79-23.2 21.7 11.8 47.1 19.5 64 19.5 29.2 0 31.2-32 19.7-43.4-13.9-13.6-54.3-9.7-73.6-7.2zM377 105L279 7c-4.5-4.5-10.6-7-17-7h-6v128h128v-6.1c0-6.3-2.5-12.4-7-16.9zm-74.1 255.3c4.1-2.7-2.5-11.9-42.8-9 37.1 15.8 42.8 9 42.8 9z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver productos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2d914c6\" data-id=\"2d914c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c4977dc elementor-widget elementor-widget-text-editor\" data-id=\"2c4977dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">La miner\u00eda es una de las industrias m\u00e1s reguladas, y con raz\u00f3n. Mientras la demanda mundial de minerales de alto valor aumenta constantemente, es natural que los operadores mineros busquen mejores formas de extraer y procesar las materias primas.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">Hoy en d\u00eda, con los avances en el equipamiento minero, algunas minas pueden funcionar de forma pr\u00e1cticamente aut\u00f3noma. Los equipos avanzados pueden realizar muchas de las operaciones mineras clave en determinados casos, reduciendo las preocupaciones de seguridad de los trabajadores y de las personas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cuando una mina funciona con gran autonom\u00eda gracias a la tecnolog\u00eda, la supervisi\u00f3n por v\u00eddeo es vital. Aunque la mayor\u00eda de las veces el proceso funciona por s\u00ed solo, cualquier problema que surja debe identificarse pronto y solucionarse de inmediato.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">Echemos un vistazo a algunos de los retos m\u00e1s comunes a los que se enfrentan los operadores de minas y descubramos c\u00f3mo puede ayudar la videovigilancia.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Garantizar la visibilidad en zonas poco iluminadas y polvorientas<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Solemos pensar que las minas son t\u00faneles oscuros bajo tierra. Aunque no todas las minas son subterr\u00e1neas o est\u00e1n hechas de t\u00faneles, la mala visibilidad es una caracter\u00edstica que comparten.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">En el caso de las operaciones mineras automatizadas, esto significa que las c\u00e1maras de v\u00eddeo deben ser capaces de grabar im\u00e1genes en condiciones dif\u00edciles de ver y tambi\u00e9n deben resistir el polvo y los desechos del duro entorno minero. Con las c\u00e1maras de Opticom, los componentes de v\u00eddeo sensibles est\u00e1n rodeados por una carcasa de aleaci\u00f3n de titanio pr\u00e1cticamente indestructible, que los protege del polvo, la humedad, las vibraciones y las temperaturas extremas. La vigilancia por v\u00eddeo de las minas requiere c\u00e1maras robustas que no necesiten ser sustituidas cuando se exponen a un poco de polvo.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Mejor funcionamiento y gesti\u00f3n de las m\u00e1quinas gracias a la supervisi\u00f3n por v\u00eddeo<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Los sistemas de videovigilancia industrial permiten a los operadores supervisar las operaciones de la mina desde lejos para identificar y alertar sobre cualquier problema potencial. Esto ahorra tiempo, dinero y seguridad a los trabajadores.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">En la miner\u00eda aut\u00f3noma, un problema que suele surgir es el sobrecalentamiento de los equipos. Aqu\u00ed es donde entra en juego la supervisi\u00f3n por v\u00eddeo t\u00e9rmico. La supervisi\u00f3n por v\u00eddeo t\u00e9rmico puede ayudar a identificar si la maquinaria se est\u00e1 sobrecalentando o, en el otro extremo, si est\u00e1 fr\u00eda y no funciona como se espera. Estos sistemas pueden ayudar a evitar accidentes graves, explosiones y fallos en los equipos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Las c\u00e1maras t\u00e9rmicas pueden controlar la temperatura de los equipos, y los operarios pueden vigilar que las temperaturas se mantengan en los rangos previstos. Si se produce un sobrecalentamiento, el equipo puede apagarse, repararse y volver a ponerse en l\u00ednea, en lugar de dejar que el sobrecalentamiento provoque un fallo del equipo o incluso una explosi\u00f3n.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">Los equipos mineros aut\u00f3nomos son caros, y evitar que se sobrecalienten controlando su estado t\u00e9rmico puede alargar su vida \u00fatil y ahorrar dinero. Cualquier problema con los equipos de miner\u00eda cuesta tiempo y dinero, por lo que los operadores optan por la supervisi\u00f3n por v\u00eddeo t\u00e9rmico y el env\u00edo de im\u00e1genes a trav\u00e9s de IP, Wifi, etc. a estaciones de supervisi\u00f3n remotas.  <\/span><\/p>\n<h2><span style=\"font-weight: 400\">Soluciones de videovigilancia para la industria minera de Opticom<\/span><\/h2>\n<p><span style=\"font-weight: 400\">En Opticom, somos especialistas en la creaci\u00f3n de equipos de v\u00eddeo resistentes para la industria minera. Todas nuestras c\u00e1maras y accesorios est\u00e1n dise\u00f1ados para soportar los entornos m\u00e1s duros y para ayudarle a garantizar el tiempo de actividad y la productividad de sus operaciones mineras.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Algunas de nuestras c\u00e1maras m\u00e1s vendidas para la industria minera son:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/opticomtech.comes\/producto\/cc02-camara\/\"><br \/>\n  <span style=\"font-weight: 400\">CC02<\/span><br \/>\n<\/a><span style=\"font-weight: 400\"> C\u00e1mara anal\u00f3gica industrial robusta<\/span><\/li>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/opticomtech.comes\/producto\/cc04-ip2mv\/\"><br \/>\n  <span style=\"font-weight: 400\">CC04-IP2MV<\/span><br \/>\n<\/a><span style=\"font-weight: 400\"> C\u00e1mara industrial robusta de alta definici\u00f3n para redes IP<\/span><\/li>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/opticomtech.comes\/producto\/cc04-ip3mv\/\"><br \/>\n  <span style=\"font-weight: 400\">CC04-IP3MV<\/span><br \/>\n<\/a><span style=\"font-weight: 400\"> C\u00e1mara industrial robusta de alta definici\u00f3n para redes IP<\/span><\/li>\n<li style=\"font-weight: 400\"><a href=\"https:\/\/opticomtech.comes\/producto\/cc06-hb36f\/\"><br \/>\n  <span style=\"font-weight: 400\">CC06-HB36F<\/span><br \/>\n<\/a><span style=\"font-weight: 400\"> C\u00e1mara anal\u00f3gica de acero inoxidable AISI SS316<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">\u00bfNo est\u00e1 seguro de que sean la opci\u00f3n adecuada para su mina? Estaremos encantados de asesorarle sobre las mejores soluciones de videovigilancia y termograf\u00eda.  <\/span><a href=\"https:\/\/opticomtech.comes\/contacto\/\"><span style=\"font-weight: 400\">Ponte en contacto.<\/span><\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sistemas de c\u00e1maras construidos para durar<\/p>\n","protected":false},"author":8,"featured_media":3461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[161],"tags":[],"class_list":["post-3467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo mejorar las operaciones mineras con la videovigilancia - Opticom Technologies<\/title>\n<meta name=\"description\" content=\"La supervisi\u00f3n por v\u00eddeo puede evitar accidentes graves en el sector minero, agilizar las operaciones y mejorar la productividad. M\u00e1s informaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo mejorar las operaciones mineras con la videovigilancia - Opticom Technologies\" \/>\n<meta property=\"og:description\" content=\"La supervisi\u00f3n por v\u00eddeo puede evitar accidentes graves en el sector minero, agilizar las operaciones y mejorar la productividad. M\u00e1s informaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/\" \/>\n<meta property=\"og:site_name\" content=\"Opticom Technologies\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-09T07:09:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-13T21:58:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring-1024x682.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Megan Horn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Megan Horn\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/\"},\"author\":{\"name\":\"Megan Horn\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#\\\/schema\\\/person\\\/c3acc9b6164ae8121373536f865d50f4\"},\"headline\":\"C\u00f3mo mejorar las operaciones mineras con la videovigilancia\",\"datePublished\":\"2022-11-09T07:09:22+00:00\",\"dateModified\":\"2022-11-13T21:58:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/\"},\"wordCount\":748,\"publisher\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/mining-video-monitoring.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/\",\"name\":\"C\u00f3mo mejorar las operaciones mineras con la videovigilancia - Opticom Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/mining-video-monitoring.jpg\",\"datePublished\":\"2022-11-09T07:09:22+00:00\",\"dateModified\":\"2022-11-13T21:58:26+00:00\",\"description\":\"La supervisi\u00f3n por v\u00eddeo puede evitar accidentes graves en el sector minero, agilizar las operaciones y mejorar la productividad. M\u00e1s informaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/mining-video-monitoring.jpg\",\"contentUrl\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/mining-video-monitoring.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Cintas transportadoras y equipos de miner\u00eda en una cantera\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/opticomtech.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo mejorar las operaciones mineras con la videovigilancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#website\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/\",\"name\":\"Opticom Technologies\",\"description\":\"Industrial CCTV Specialists - Providing a Complete Line of Video Surveillance Products.\",\"publisher\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/opticomtech.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#organization\",\"name\":\"Opticom Technologies\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cropped-opticom_logo_2020-silver.png\",\"contentUrl\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cropped-opticom_logo_2020-silver.png\",\"width\":441,\"height\":144,\"caption\":\"Opticom Technologies\"},\"image\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#\\\/schema\\\/person\\\/c3acc9b6164ae8121373536f865d50f4\",\"name\":\"Megan Horn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g\",\"caption\":\"Megan Horn\"},\"url\":\"https:\\\/\\\/opticomtech.com\\\/es\\\/author\\\/megan-h\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo mejorar las operaciones mineras con la videovigilancia - Opticom Technologies","description":"La supervisi\u00f3n por v\u00eddeo puede evitar accidentes graves en el sector minero, agilizar las operaciones y mejorar la productividad. M\u00e1s informaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo mejorar las operaciones mineras con la videovigilancia - Opticom Technologies","og_description":"La supervisi\u00f3n por v\u00eddeo puede evitar accidentes graves en el sector minero, agilizar las operaciones y mejorar la productividad. M\u00e1s informaci\u00f3n.","og_url":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/","og_site_name":"Opticom Technologies","article_published_time":"2022-11-09T07:09:22+00:00","article_modified_time":"2022-11-13T21:58:26+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring-1024x682.jpg","type":"image\/jpeg"}],"author":"Megan Horn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Megan Horn"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/#article","isPartOf":{"@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/"},"author":{"name":"Megan Horn","@id":"https:\/\/opticomtech.com\/#\/schema\/person\/c3acc9b6164ae8121373536f865d50f4"},"headline":"C\u00f3mo mejorar las operaciones mineras con la videovigilancia","datePublished":"2022-11-09T07:09:22+00:00","dateModified":"2022-11-13T21:58:26+00:00","mainEntityOfPage":{"@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/"},"wordCount":748,"publisher":{"@id":"https:\/\/opticomtech.com\/#organization"},"image":{"@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/#primaryimage"},"thumbnailUrl":"https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/","url":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/","name":"C\u00f3mo mejorar las operaciones mineras con la videovigilancia - Opticom Technologies","isPartOf":{"@id":"https:\/\/opticomtech.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/#primaryimage"},"image":{"@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/#primaryimage"},"thumbnailUrl":"https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring.jpg","datePublished":"2022-11-09T07:09:22+00:00","dateModified":"2022-11-13T21:58:26+00:00","description":"La supervisi\u00f3n por v\u00eddeo puede evitar accidentes graves en el sector minero, agilizar las operaciones y mejorar la productividad. M\u00e1s informaci\u00f3n.","breadcrumb":{"@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/#primaryimage","url":"https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring.jpg","contentUrl":"https:\/\/opticomtech.com\/wp-content\/uploads\/2022\/11\/mining-video-monitoring.jpg","width":2000,"height":1333,"caption":"Cintas transportadoras y equipos de miner\u00eda en una cantera"},{"@type":"BreadcrumbList","@id":"https:\/\/opticomtech.com\/es\/como-mejorar-las-operaciones-mineras-con-la-videovigilancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/opticomtech.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo mejorar las operaciones mineras con la videovigilancia"}]},{"@type":"WebSite","@id":"https:\/\/opticomtech.com\/#website","url":"https:\/\/opticomtech.com\/","name":"Opticom Technologies","description":"Industrial CCTV Specialists - Providing a Complete Line of Video Surveillance Products.","publisher":{"@id":"https:\/\/opticomtech.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/opticomtech.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/opticomtech.com\/#organization","name":"Opticom Technologies","url":"https:\/\/opticomtech.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/opticomtech.com\/#\/schema\/logo\/image\/","url":"https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/cropped-opticom_logo_2020-silver.png","contentUrl":"https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/cropped-opticom_logo_2020-silver.png","width":441,"height":144,"caption":"Opticom Technologies"},"image":{"@id":"https:\/\/opticomtech.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/opticomtech.com\/#\/schema\/person\/c3acc9b6164ae8121373536f865d50f4","name":"Megan Horn","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g","caption":"Megan Horn"},"url":"https:\/\/opticomtech.com\/es\/author\/megan-h\/"}]}},"_links":{"self":[{"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/posts\/3467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/comments?post=3467"}],"version-history":[{"count":6,"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/posts\/3467\/revisions"}],"predecessor-version":[{"id":3473,"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/posts\/3467\/revisions\/3473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/media\/3461"}],"wp:attachment":[{"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/media?parent=3467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/categories?post=3467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/opticomtech.com\/es\/wp-json\/wp\/v2\/tags?post=3467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}