{"id":6079,"date":"2023-10-25T15:03:43","date_gmt":"2023-10-25T15:03:43","guid":{"rendered":"https:\/\/opticomtech.com\/surveillance-video-des-scieries-defis-et-solutions\/"},"modified":"2023-10-25T15:06:43","modified_gmt":"2023-10-25T15:06:43","slug":"surveillance-video-des-scieries-defis-et-solutions","status":"publish","type":"post","link":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/","title":{"rendered":"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6079\" class=\"elementor elementor-6079 elementor-6044\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dd94143 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dd94143\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-daf32fc\" data-id=\"daf32fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2691291f\" data-id=\"2691291f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-578f354 elementor-widget elementor-widget-image\" data-id=\"578f354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"419\" src=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-Sawmill-Challenges-Solution-1024x536.png\" class=\"attachment-large size-large wp-image-6046\" alt=\"Opticom Sawmill Video Monitoring Challenges Solution\" srcset=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-Sawmill-Challenges-Solution-1024x536.png 1024w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-Sawmill-Challenges-Solution-300x157.png 300w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-Sawmill-Challenges-Solution-768x402.png 768w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-Sawmill-Challenges-Solution-600x314.png 600w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-Sawmill-Challenges-Solution.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d0cd2ee elementor-widget elementor-widget-text-editor\" data-id=\"7d0cd2ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Il existe peu d&rsquo;environnements aussi difficiles que les scieries pour la vid\u00e9osurveillance. Dans une scierie, la pr\u00e9cision doit aller de pair avec la productivit\u00e9, et un syst\u00e8me de vid\u00e9osurveillance doit soutenir ces deux objectifs.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cependant, dans la cacophonie des machines lourdes et les d\u00e9fis inh\u00e9rents aux environnements difficiles, la mise en \u0153uvre d&rsquo;un syst\u00e8me de vid\u00e9osurveillance n&rsquo;est pas une mince affaire. Les scieries pr\u00e9sentent des d\u00e9fis uniques, qu&rsquo;il s&rsquo;agisse de conditions de travail extr\u00eames, d&rsquo;air empoussi\u00e9r\u00e9, de zones inaccessibles ou de processus de production dynamiques.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">Pouvez-vous donc cr\u00e9er un syst\u00e8me de surveillance vid\u00e9o qui favorise une productivit\u00e9 sans faille dans les scieries ? Notre exp\u00e9rience de plus de 50 ans dans ce domaine pr\u00e9cis nous permet de r\u00e9pondre par l&rsquo;affirmative. Nous aimons les d\u00e9fis, c&rsquo;est pourquoi nous sommes le fournisseur privil\u00e9gi\u00e9 de solutions de vid\u00e9osurveillance pour les scieries.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nous travaillons avec les responsables \u00e9lectriques des scieries presque tous les jours, et nous connaissons donc parfaitement les d\u00e9fis qu&rsquo;ils doivent relever. Voici quelques-uns des probl\u00e8mes que vous rencontrerez fr\u00e9quemment lors de la mise en place d&rsquo;un syst\u00e8me de vid\u00e9osurveillance pour les scieries, ainsi que la mani\u00e8re de les surmonter.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Les d\u00e9fis de la surveillance vid\u00e9o des scieries<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Dans les scieries, la surveillance vid\u00e9o doit s&rsquo;adapter \u00e0 l&rsquo;environnement, et non l&rsquo;inverse. Vous fabriquez des produits con\u00e7us pour r\u00e9sister \u00e0 l&rsquo;environnement, et nous faisons de m\u00eame. Tout aussi important, nos produits de vid\u00e9osurveillance font de la surveillance un jeu d&rsquo;enfant, et non une nouvelle t\u00e2che difficile.<\/span><\/p>\n<h3><span style=\"font-weight: 400\">1. Montage de cam\u00e9ras sur des machines lourdes et soumises \u00e0 de fortes vibrations<\/span><\/h3>\n<p><span style=\"font-weight: 400\">Les \u00e9quipements des scieries ont des niveaux de vibration et de bruit incroyablement \u00e9lev\u00e9s, qui sont tous deux tr\u00e8s nocifs pour les d\u00e9licates subtilit\u00e9s des cam\u00e9ras vid\u00e9o. Avant de travailler avec Opticom, la plupart des responsables \u00e9lectriques des scieries devaient utiliser des solutions de fortune, comme le montage des cam\u00e9ras sur les chevrons, ou devaient remplacer leurs cam\u00e9ras toutes les quelques semaines !  <\/span><\/p>\n<p><span style=\"font-weight: 400\">L&rsquo;installation de cam\u00e9ras dans les combles ou dans d&rsquo;autres endroits peu recommandables n&rsquo;est pas seulement encombrante, elle r\u00e9duit \u00e9galement la qualit\u00e9 de votre flux vid\u00e9o. Si vous \u00eates limit\u00e9 dans l&#8217;emplacement des cam\u00e9ras parce qu&rsquo;elles sont fragiles, les cam\u00e9ras ne peuvent pas capturer les angles vid\u00e9o ou la qualit\u00e9 que vous souhaitez et dont vous avez besoin.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les cam\u00e9ras industrielles robustes d&rsquo;Opticom, comme la <\/span><a href=\"https:\/\/opticomtech.com\/fr\/produit\/cc02-camera\/\"><br \/>\n  <span style=\"font-weight: 400\">CC02<\/span><br \/>\n<\/a><span style=\"font-weight: 400\"> et <\/span><a href=\"https:\/\/opticomtech.com\/fr\/?attachment_id=4457\"><br \/>\n  <span style=\"font-weight: 400\">CC04<\/span><br \/>\n<\/a><span style=\"font-weight: 400\">par exemple, sont sp\u00e9cialement con\u00e7us pour r\u00e9sister \u00e0 des niveaux \u00e9lev\u00e9s de vibrations, m\u00eame celles des machines lourdes comme celles d&rsquo;une scierie. Vous pouvez monter les cam\u00e9ras Opticom directement sur l&rsquo;\u00e9quipement de votre scierie, comme par exemple le syst\u00e8me d&rsquo;alarme.  <\/span><a href=\"https:\/\/opticomtech.com\/fr\/des-cameras-video-capables-de-resister-aux-vibrations-de-lecorceuse-de-grumes\/\"><span style=\"font-weight: 400\">sur un \u00e9corceur de grumes<\/span><\/a><span style=\"font-weight: 400\">  ou de la d\u00e9chiqueteuse et des cantors int\u00e9rieurs pour obtenir tous les angles et toutes les vues dont vous avez besoin. L&rsquo;utilisation d&rsquo;un  <\/span><a href=\"https:\/\/opticomtech.com\/fr\/comment-les-supports-antivibratoires-augmentent-la-duree-de-vie-de-vos-cameras-video-de-scierie\/\"><br \/>\n  <span style=\"font-weight: 400\">support anti-vibrations<\/span><br \/>\n<\/a><span style=\"font-weight: 400\"> permet une plus grande souplesse d&rsquo;installation et prot\u00e8ge davantage l&rsquo;appareil photo des risques li\u00e9s aux scieries.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc9bf25 elementor-widget elementor-widget-image\" data-id=\"bc9bf25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"555\" src=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-camera-mounted-to-watch-the-line-crop-1024x710.jpg\" class=\"attachment-large size-large wp-image-6067\" alt=\"sawmill video monitoring challenges - mounting\" srcset=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-camera-mounted-to-watch-the-line-crop-1024x710.jpg 1024w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-camera-mounted-to-watch-the-line-crop-300x208.jpg 300w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-camera-mounted-to-watch-the-line-crop-768x532.jpg 768w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-camera-mounted-to-watch-the-line-crop-1536x1065.jpg 1536w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-camera-mounted-to-watch-the-line-crop-2048x1420.jpg 2048w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-camera-mounted-to-watch-the-line-crop-600x416.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c23eda7 elementor-widget elementor-widget-text-editor\" data-id=\"c23eda7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Les cam\u00e9ras mont\u00e9es sur les \u00e9quipements n&rsquo;interf\u00e8rent en aucune mani\u00e8re avec la machine, et leur alimentation peut \u00eatre facilement suivie par un op\u00e9rateur \u00e0 distance disposant de la meilleure vue sur les op\u00e9rations de l&rsquo;usine.<\/span><\/p>\n<h3><span style=\"font-weight: 400\">2. Les cam\u00e9ras commerciales doivent \u00eatre remplac\u00e9es fr\u00e9quemment<\/span><\/h3>\n<p><span style=\"font-weight: 400\">Les cam\u00e9ras disponibles sur le march\u00e9 sont certes tr\u00e8s bon march\u00e9, mais elles ne tardent pas \u00e0 se briser ou \u00e0 tomber en panne dans une scierie. Compte tenu de la quantit\u00e9 de poussi\u00e8re, de d\u00e9bris et de vibrations dans une scierie, certains appareils photo ne durent pas plus d&rsquo;une semaine. (Vraiment&#8230; nous avons eu des clients qui, avant Opticom, \u00e9taient  <\/span><a href=\"https:\/\/opticomtech.com\/fr\/arretez-de-remplacer-les-cameras-des-scieries-tous-les-deux-mois-il-existe-une-meilleure-solution\/\"><br \/>\n  <span style=\"font-weight: 400\">remplacer les cam\u00e9ras presque chaque semaine<\/span><br \/>\n<\/a><span style=\"font-weight: 400\">.)<\/span><\/p>\n<p><span style=\"font-weight: 400\">Si vous installez des cam\u00e9ras standard, vous finirez par payer beaucoup plus cher pour les remplacer chaque semaine ou chaque mois. Il faut tenir compte \u00e0 la fois du co\u00fbt des cam\u00e9ras, du co\u00fbt de la main-d&rsquo;\u0153uvre pour les remplacer et, bien s\u00fbr, du temps d&rsquo;arr\u00eat des lignes pendant que les cam\u00e9ras sont hors ligne.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">Les cam\u00e9ras Opticom sont robustes et sp\u00e9cialement con\u00e7ues pour l&rsquo;environnement difficile d&rsquo;une scierie. Ils durent des ann\u00e9es, pas des mois,  <\/span><a href=\"https:\/\/opticomtech.com\/fr\/comment-reduire-le-cout-de-possession-des-systemes-de-videosurveillance-industrielle\/\"><br \/>\n  <span style=\"font-weight: 400\">en r\u00e9duisant votre co\u00fbt total de possession<\/span><br \/>\n<\/a><span style=\"font-weight: 400\"> presque imm\u00e9diatement. <\/span> <\/p>\n<h3><span style=\"font-weight: 400\">3. Les cam\u00e9ras sont touch\u00e9es par les journaux<\/span><\/h3>\n<p><span style=\"font-weight: 400\">Les scieries ne sont pas faites pour les \u00e2mes sensibles. Les d\u00e9bris, les grumes et les planches se d\u00e9placent rapidement autour de l&rsquo;usine. Les cam\u00e9ras, lorsqu&rsquo;elles sont bien plac\u00e9es, sont au c\u0153ur de l&rsquo;action. Il y a donc toujours un risque qu&rsquo;ils soient heurt\u00e9s par des d\u00e9bris ou m\u00eame par un rondin ou une planche.<\/span><\/p>\n<p><span style=\"font-weight: 400\">En fait, cela s&rsquo;est produit &#8211; plus d&rsquo;une fois.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">Lorsque nous disons que les cam\u00e9ras Opticom peuvent r\u00e9sister \u00e0 presque tout, nous le pensons litt\u00e9ralement. La vid\u00e9o ci-dessous nous a \u00e9t\u00e9 envoy\u00e9e par un client et elle montre exactement ce qui arrive \u00e0 un  <\/span><a href=\"https:\/\/opticomtech.com\/fr\/que-faire-lorsque-la-camera-de-votre-scierie-est-heurtee-par-une-grume\/\"><br \/>\n  <span style=\"font-weight: 400\">appareil photo percut\u00e9 par une grume<\/span><br \/>\n<\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-647e1fc elementor-widget elementor-widget-video\" data-id=\"647e1fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=f4UAQxxw64U&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-760b889 elementor-widget elementor-widget-text-editor\" data-id=\"760b889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Comme vous pouvez le constater, rien n&rsquo;est arriv\u00e9 \u00e0 l&rsquo;appareil, il est toujours en parfait \u00e9tat de marche. La seule chose qui devait \u00eatre remplac\u00e9e \u00e9tait le support de vibration.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ce n&rsquo;est pas la seule fois. Nous avons \u00e9galement \u00e9cras\u00e9 des cam\u00e9ras Opticom avec un camion, et l&rsquo;une d&rsquo;entre elles a \u00e9t\u00e9 transperc\u00e9e par une planche. L\u00e0 encore, la cam\u00e9ra fonctionne toujours et seul le support de vibration a d\u00fb \u00eatre remplac\u00e9. Voici une photo de la cam\u00e9ra CC04 apr\u00e8s un impact direct :<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d8cdd6 elementor-widget elementor-widget-image\" data-id=\"5d8cdd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/IMG_1052001-1024x768.jpg\" class=\"attachment-large size-large wp-image-6064\" alt=\"Opticom camera speared by board in sawmill\" srcset=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/IMG_1052001-1024x768.jpg 1024w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/IMG_1052001-300x225.jpg 300w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/IMG_1052001-768x576.jpg 768w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/IMG_1052001-1536x1152.jpg 1536w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/IMG_1052001-600x450.jpg 600w, https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/IMG_1052001.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20487d3 elementor-widget elementor-widget-text-editor\" data-id=\"20487d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">Il se passe des choses dans les scieries. C&rsquo;est pourquoi vous avez besoin de cam\u00e9ras Opticom industrielles et robustes, capables de r\u00e9sister \u00e0 tout ce qu&rsquo;on leur lance&#8230; litt\u00e9ralement.<\/span><\/p>\n<h3><span style=\"font-weight: 400\">4. Surveillance vid\u00e9o \u00e0 distance dans les scieries<\/span><\/h3>\n<p><span style=\"font-weight: 400\">Autour des machines lourdes, les accidents et les incidents sont fr\u00e9quents. Vous voulez r\u00e9duire ces risques au minimum, et la derni\u00e8re chose que vous voulez faire est d&rsquo;ajouter du personnel \u00e0 proximit\u00e9 de ces risques.<\/span><\/p>\n<p><span style=\"font-weight: 400\">C&rsquo;est pourquoi les scieries ont besoin d&rsquo;une solution solide de surveillance vid\u00e9o \u00e0 distance.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">Gr\u00e2ce \u00e0 la technologie Opticom, il suffit d&rsquo;une cabine d&rsquo;op\u00e9rateur situ\u00e9e \u00e0 une distance s\u00fbre des troncs et des d\u00e9bris. Ils peuvent surveiller l&rsquo;activit\u00e9 \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;usine sur leurs flux vid\u00e9o en r\u00e9seau et intervenir lorsqu&rsquo;ils rep\u00e8rent une pi\u00e8ce de machinerie potentiellement d\u00e9fectueuse ou un incident imminent.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La surveillance \u00e0 distance ne s&rsquo;arr\u00eate pas aux murs de l&rsquo;usine : les op\u00e9rateurs et les responsables peuvent \u00e9galement visualiser les flux vid\u00e9o sur une application mobile pour voir les op\u00e9rations en temps r\u00e9el. Il suffit de t\u00e9l\u00e9charger une application, de la connecter aux flux vid\u00e9o de votre usine et de visualiser les op\u00e9rations en toute s\u00e9curit\u00e9 pendant vos d\u00e9placements.<\/span><\/p>\n<h3><span style=\"font-weight: 400\">5. Difficile d&rsquo;obtenir des vues rapproch\u00e9es des op\u00e9rations<\/span><\/h3>\n<p><span style=\"font-weight: 400\">S&rsquo;il est assez facile de surveiller les op\u00e9rations de chargement et les autres t\u00e2ches habituellement effectu\u00e9es en dehors du \u00ab\u00a0c\u0153ur\u00a0\u00bb d&rsquo;une scierie, il est un peu plus difficile d&rsquo;obtenir des images de la ligne, \u00e0 moins d&rsquo;\u00eatre \u00e9quip\u00e9 de cam\u00e9ras Opticom.  <\/span><\/p>\n<p><span style=\"font-weight: 400\">Comme indiqu\u00e9 pr\u00e9c\u00e9demment, les cam\u00e9ras du commerce ne peuvent tout simplement pas \u00eatre mont\u00e9es sur les \u00e9quipements ou, parfois, \u00e0 proximit\u00e9 de ceux-ci. Les responsables \u00e9lectriques font tout ce qu&rsquo;ils peuvent pour obtenir des vues de la ligne &#8211; montage dans les chevrons, montage \u00e9loign\u00e9 et zoom sur une sortie de faible qualit\u00e9, etc.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les cam\u00e9ras Opticom peuvent \u00eatre mont\u00e9es dans les espaces les plus difficiles et les plus robustes. De cette fa\u00e7on, vous pouvez :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">D\u00e9tecter le plus t\u00f4t possible les probl\u00e8mes potentiels li\u00e9s aux machines<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">\u00c9viter les accidents et les incidents divers<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">\u00c9viter les temps d&rsquo;arr\u00eat co\u00fbteux<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Assurer la s\u00e9curit\u00e9 des travailleurs<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Vous disposez d&rsquo;une vue compl\u00e8te et en temps r\u00e9el de l&rsquo;\u00e9quipement de votre scierie, ce qui vous permet de l&rsquo;utiliser en toute s\u00e9curit\u00e9 et en toute transparence. D\u00e9couvrez l&rsquo;installation de l&rsquo;un de nos clients scieurs. Il est s\u00fbr, s\u00e9curis\u00e9 et efficace.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49b548d elementor-widget elementor-widget-image\" data-id=\"49b548d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/opticomtech.com\/wp-content\/uploads\/elementor\/thumbs\/Opticom-operator-in-booth-scaled-qedxocsoibqe9p58oo2i3p0ruehsnua4n6kp172spe.jpg\" title=\"Opticom operator in booth\" alt=\"Sawmill Video Monitoring Challenges Opticom\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-460adf4 elementor-widget elementor-widget-text-editor\" data-id=\"460adf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"font-weight: 400\">Choisir le bon syst\u00e8me de vid\u00e9osurveillance pour les scieries<\/span><\/h2>\n<p><span style=\"font-weight: 400\">Bien qu&rsquo;il s&rsquo;agisse l\u00e0 de quelques-uns des d\u00e9fis les plus courants que nous avons rencontr\u00e9s dans le cadre de la vid\u00e9osurveillance des scieries, nous savons que chaque scierie est unique et a des besoins qui lui sont propres. C&rsquo;est pourquoi les repr\u00e9sentants d&rsquo;Opticom s&rsquo;efforcent de comprendre les besoins sp\u00e9cifiques de votre scierie et recommandent des cam\u00e9ras, des moniteurs, des r\u00e9seaux, l&#8217;emplacement des cam\u00e9ras, et plus encore, sp\u00e9cifiquement pour votre scierie.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Vous voulez \u00eatre s\u00fbr de tirer le meilleur parti de votre syst\u00e8me de vid\u00e9osurveillance pour scieries ? <\/span><a href=\"https:\/\/opticomtech.com\/fr\/contact\/\"><br \/>\n  <span style=\"font-weight: 400\">Parlez-en \u00e0 nos consultants<\/span><br \/>\n<\/a><span style=\"font-weight: 400\">-nous vous recommanderons une solution qui vous permettra de relever vos d\u00e9fis.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Des solutions vid\u00e9o con\u00e7ues pour les scieries<\/p>\n","protected":false},"author":8,"featured_media":6057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[],"class_list":["post-6079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions - Opticom Technologies<\/title>\n<meta name=\"description\" content=\"La vid\u00e9osurveillance dans les scieries pr\u00e9sente des d\u00e9fis particuliers : \u00e9quipements qui vibrent beaucoup, d\u00e9bris, sciure qui ab\u00eeme les cam\u00e9ras, etc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions - Opticom Technologies\" \/>\n<meta property=\"og:description\" content=\"La vid\u00e9osurveillance dans les scieries pr\u00e9sente des d\u00e9fis particuliers : \u00e9quipements qui vibrent beaucoup, d\u00e9bris, sciure qui ab\u00eeme les cam\u00e9ras, etc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/\" \/>\n<meta property=\"og:site_name\" content=\"Opticom Technologies\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-25T15:03:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-25T15:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-operator-in-booth-thumb-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Megan Horn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Megan Horn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/\"},\"author\":{\"name\":\"Megan Horn\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#\\\/schema\\\/person\\\/c3acc9b6164ae8121373536f865d50f4\"},\"headline\":\"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions\",\"datePublished\":\"2023-10-25T15:03:43+00:00\",\"dateModified\":\"2023-10-25T15:06:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/\"},\"wordCount\":1607,\"publisher\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Opticom-operator-in-booth-thumb-1.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/\",\"name\":\"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions - Opticom Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Opticom-operator-in-booth-thumb-1.jpg\",\"datePublished\":\"2023-10-25T15:03:43+00:00\",\"dateModified\":\"2023-10-25T15:06:43+00:00\",\"description\":\"La vid\u00e9osurveillance dans les scieries pr\u00e9sente des d\u00e9fis particuliers : \u00e9quipements qui vibrent beaucoup, d\u00e9bris, sciure qui ab\u00eeme les cam\u00e9ras, etc.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/#primaryimage\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Opticom-operator-in-booth-thumb-1.jpg\",\"contentUrl\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Opticom-operator-in-booth-thumb-1.jpg\",\"width\":1200,\"height\":1068,\"caption\":\"Opticom video monitoring challenges\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/surveillance-video-des-scieries-defis-et-solutions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/opticomtech.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#website\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/\",\"name\":\"Opticom Technologies\",\"description\":\"Industrial CCTV Specialists - Providing a Complete Line of Video Surveillance Products.\",\"publisher\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/opticomtech.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#organization\",\"name\":\"Opticom Technologies\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cropped-opticom_logo_2020-silver.png\",\"contentUrl\":\"https:\\\/\\\/opticomtech.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/cropped-opticom_logo_2020-silver.png\",\"width\":441,\"height\":144,\"caption\":\"Opticom Technologies\"},\"image\":{\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/opticomtech.com\\\/#\\\/schema\\\/person\\\/c3acc9b6164ae8121373536f865d50f4\",\"name\":\"Megan Horn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g\",\"caption\":\"Megan Horn\"},\"url\":\"https:\\\/\\\/opticomtech.com\\\/fr\\\/author\\\/megan-h\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions - Opticom Technologies","description":"La vid\u00e9osurveillance dans les scieries pr\u00e9sente des d\u00e9fis particuliers : \u00e9quipements qui vibrent beaucoup, d\u00e9bris, sciure qui ab\u00eeme les cam\u00e9ras, etc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/","og_locale":"fr_FR","og_type":"article","og_title":"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions - Opticom Technologies","og_description":"La vid\u00e9osurveillance dans les scieries pr\u00e9sente des d\u00e9fis particuliers : \u00e9quipements qui vibrent beaucoup, d\u00e9bris, sciure qui ab\u00eeme les cam\u00e9ras, etc.","og_url":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/","og_site_name":"Opticom Technologies","article_published_time":"2023-10-25T15:03:43+00:00","article_modified_time":"2023-10-25T15:06:43+00:00","og_image":[{"width":1200,"height":1068,"url":"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-operator-in-booth-thumb-1.jpg","type":"image\/jpeg"}],"author":"Megan Horn","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Megan Horn","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/#article","isPartOf":{"@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/"},"author":{"name":"Megan Horn","@id":"https:\/\/opticomtech.com\/#\/schema\/person\/c3acc9b6164ae8121373536f865d50f4"},"headline":"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions","datePublished":"2023-10-25T15:03:43+00:00","dateModified":"2023-10-25T15:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/"},"wordCount":1607,"publisher":{"@id":"https:\/\/opticomtech.com\/#organization"},"image":{"@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/#primaryimage"},"thumbnailUrl":"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-operator-in-booth-thumb-1.jpg","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/","url":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/","name":"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions - Opticom Technologies","isPartOf":{"@id":"https:\/\/opticomtech.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/#primaryimage"},"image":{"@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/#primaryimage"},"thumbnailUrl":"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-operator-in-booth-thumb-1.jpg","datePublished":"2023-10-25T15:03:43+00:00","dateModified":"2023-10-25T15:06:43+00:00","description":"La vid\u00e9osurveillance dans les scieries pr\u00e9sente des d\u00e9fis particuliers : \u00e9quipements qui vibrent beaucoup, d\u00e9bris, sciure qui ab\u00eeme les cam\u00e9ras, etc.","breadcrumb":{"@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/#primaryimage","url":"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-operator-in-booth-thumb-1.jpg","contentUrl":"https:\/\/opticomtech.com\/wp-content\/uploads\/2023\/10\/Opticom-operator-in-booth-thumb-1.jpg","width":1200,"height":1068,"caption":"Opticom video monitoring challenges"},{"@type":"BreadcrumbList","@id":"https:\/\/opticomtech.com\/fr\/surveillance-video-des-scieries-defis-et-solutions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/opticomtech.com\/"},{"@type":"ListItem","position":2,"name":"Surveillance vid\u00e9o des scieries : D\u00e9fis et solutions"}]},{"@type":"WebSite","@id":"https:\/\/opticomtech.com\/#website","url":"https:\/\/opticomtech.com\/","name":"Opticom Technologies","description":"Industrial CCTV Specialists - Providing a Complete Line of Video Surveillance Products.","publisher":{"@id":"https:\/\/opticomtech.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/opticomtech.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/opticomtech.com\/#organization","name":"Opticom Technologies","url":"https:\/\/opticomtech.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/opticomtech.com\/#\/schema\/logo\/image\/","url":"https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/cropped-opticom_logo_2020-silver.png","contentUrl":"https:\/\/opticomtech.com\/wp-content\/uploads\/2020\/08\/cropped-opticom_logo_2020-silver.png","width":441,"height":144,"caption":"Opticom Technologies"},"image":{"@id":"https:\/\/opticomtech.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/opticomtech.com\/#\/schema\/person\/c3acc9b6164ae8121373536f865d50f4","name":"Megan Horn","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e5ce1f3de27e7efe24164844d7f10dbe0048baf0fd28526dcb8c86216e18981?s=96&d=mm&r=g","caption":"Megan Horn"},"url":"https:\/\/opticomtech.com\/fr\/author\/megan-h\/"}]}},"_links":{"self":[{"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/posts\/6079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/comments?post=6079"}],"version-history":[{"count":4,"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/posts\/6079\/revisions"}],"predecessor-version":[{"id":6090,"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/posts\/6079\/revisions\/6090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/media\/6057"}],"wp:attachment":[{"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/media?parent=6079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/categories?post=6079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/opticomtech.com\/fr\/wp-json\/wp\/v2\/tags?post=6079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}